{"id":63653,"date":"2024-10-24T22:00:15","date_gmt":"2024-10-24T22:00:15","guid":{"rendered":"https:\/\/epicadventurescr.com\/parque-nacional-del-corcovado-con-epic-adventures-costa-rica\/"},"modified":"2026-03-16T01:41:14","modified_gmt":"2026-03-16T01:41:14","slug":"parque-nacional-del-corcovado-con-epic-adventures-costa-rica","status":"publish","type":"post","link":"https:\/\/epicadventurescr.com\/es\/parque-nacional-del-corcovado-con-epic-adventures-costa-rica\/","title":{"rendered":"Parque Nacional del Corcovado con Epic Adventures Costa Rica"},"content":{"rendered":"<h2 aria-live=\"polite\" aria-atomic=\"true\">El Parque Nacional del Corcovado es un testimonio de la belleza natural y la biodiversidad de Costa Rica. Este extraordinario lugar alberga una gran variedad de especies animales y vegetales \u00fanicas y poco comunes, muchas de las cuales est\u00e1n protegidas dentro de sus l\u00edmites. <\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-63641\" src=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/10-1.jpg\" alt=\"Parque Nacional Corcovado\" width=\"1300\" height=\"1000\" srcset=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/10-1.jpg 1300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/10-1-300x231.jpg 300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/10-1-1024x788.jpg 1024w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/10-1-768x591.jpg 768w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/10-1-600x462.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\"><strong>Descubre la Belleza Natural y la Biodiversidad del Parque Nacional de Corcovado  <\/strong><\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">Emb\u00e1rcate en un viaje extraordinario con Epic Adventures Costa Rica mientras exploramos la selva tropical del Parque del Corcovado, un refugio de especies vegetales y animales raras y \u00fanicas. Este art\u00edculo profundiza en la incre\u00edble biodiversidad del parque, su importancia mundial y las inolvidables experiencias que te esperan en nuestra exclusiva excursi\u00f3n de un d\u00eda desde Manuel Antonio.   <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">\u00a1Prep\u00e1rate para sumergirte en la belleza salvaje de uno de los lugares biol\u00f3gicamente m\u00e1s intensos de la Tierra!<\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-63645\" src=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/12-1.jpg\" alt=\"Parque Nacional Corcovado\" width=\"1300\" height=\"1000\" srcset=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/12-1.jpg 1300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/12-1-300x231.jpg 300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/12-1-1024x788.jpg 1024w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/12-1-768x591.jpg 768w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/12-1-600x462.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\"><strong>Parque Nacional del Corcovado: Un Testamento para la Biodiversidad de Costa Rica<\/strong><\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">Este parque nacional es un testimonio de la belleza natural y la biodiversidad de Costa Rica. Este extraordinario lugar alberga una gran variedad de especies vegetales y animales raras y \u00fanicas, muchas de las cuales est\u00e1n protegidas dentro de sus l\u00edmites. El parque alberga las mayores poblaciones del mundo de cotinga turquesa (Cotinga ridgwayi), cotinga de pico amarillo (Carpodectes antoniae) y colibr\u00ed de los manglares (Chrysuronia boucardi).    <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">Adem\u00e1s, alberga a la hormiguera de cara negra (Habia atrimaxillaris), la orqu\u00eddea m\u00e1s peque\u00f1a de Costa Rica (Platystele tica) y la especie arb\u00f3rea m\u00e1s alta de toda Centroam\u00e9rica (Huberodendron allenii).<\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">Seg\u00fan la Universidad de Costa Rica (UCR), una hect\u00e1rea de bosque de la Pen\u00ednsula de Osa contiene m\u00e1s especies arb\u00f3reas que una superficie similar de la Amazonia brasile\u00f1a. Esto incluye gigantes como el emblem\u00e1tico ajo negro (Anthodiscus chocoensis), el cam\u00edbar (Copaifera camibar) y los reci\u00e9n descubiertos guapinoles negros (Hymenaea osanigraseminae y Prioria peninsulae). <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-63635\" src=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/16-1.jpg\" alt=\"Parque Nacional Corcovado\" width=\"1300\" height=\"1000\" srcset=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/16-1.jpg 1300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/16-1-300x231.jpg 300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/16-1-1024x788.jpg 1024w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/16-1-768x591.jpg 768w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/16-1-600x462.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">El parque protege la mayor extensi\u00f3n continua y de mayor calidad de la Selva Tropical del Pac\u00edfico, un ecosistema en peligro de extinci\u00f3n que se extiende por el sur de Costa Rica y el oeste de Panam\u00e1. Los bi\u00f3logos de la UCR destacan la naturaleza sensible y vulnerable de este ecosistema, se\u00f1alando que la Pen\u00ednsula de Osa alberga m\u00e1s del 3% de la biodiversidad del planeta.   <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">Entre 1990 y 2005, amplios esfuerzos cient\u00edficos condujeron a la descripci\u00f3n de 57 nuevas especies vegetales en la Pen\u00ednsula, 52 de las cuales son end\u00e9micas.<\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63643\" src=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/11-1.jpg\" alt=\"Parque Nacional Corcovado\" width=\"1300\" height=\"1000\" srcset=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/11-1.jpg 1300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/11-1-300x231.jpg 300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/11-1-1024x788.jpg 1024w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/11-1-768x591.jpg 768w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/11-1-600x462.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">El Parque Nacional de Corcovado y la Pen\u00ednsula de Osa han cosechado numerosos elogios internacionales. BirdLife International design\u00f3 a Corcovado \u00ab\u00c1rea Importante para las Aves\u00bb, y la National Geographic Society lo reconoci\u00f3 como el lugar biol\u00f3gicamente m\u00e1s intenso de la Tierra.   <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">Estos reconocimientos subrayan la extraordinaria importancia del parque y la responsabilidad de conservaci\u00f3n que representa para todos los costarricenses. Los especialistas de la UCR subrayan la urgente necesidad de una mayor protecci\u00f3n para salvaguardar la biodiversidad del parque. <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\"><strong>Disfruta de lo mejor del Parque Nacional del Corcovado con nuestra excursi\u00f3n de un d\u00eda<\/strong><\/span><\/p>\n<div class=\"space-y-3\"><\/div>\n<div class=\"space-y-3 \" data-content=\"ai-message\">\n<p class=\"sr-only\" aria-label=\"Copilot\"><span style=\"font-size: 16px;\">Nuestra aventura comienza temprano por la ma\u00f1ana, con la recogida en tu hotel de Manuel Antonio. A continuaci\u00f3n, nos dirigiremos a la zona de los Manglares de Sierpe para tomar un copioso desayuno antes de embarcarnos en un paseo en barco de dos horas por el sistema de manglares m\u00e1s extenso de Centroam\u00e9rica y adentrarnos en el oc\u00e9ano Pac\u00edfico. Durante este viaje, tendr\u00e1s la oportunidad de ver bancos de delfines mulares, tortugas marinas e incluso ballenas jorobadas (de julio a octubre), lo que supone un emocionante comienzo del d\u00eda.  <\/span><\/p>\n<p aria-label=\"Copilot\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63631\" src=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/14-1.jpg\" alt=\"\" width=\"1300\" height=\"1000\" srcset=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/14-1.jpg 1300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/14-1-300x231.jpg 300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/14-1-1024x788.jpg 1024w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/14-1-768x591.jpg 768w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/14-1-600x462.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<div class=\"space-y-3 break-words\">\n<p><span class=\"\">Al llegar al Parque Nacional de Corcovado, nos embarcaremos en una tranquila caminata de dos horas, que nos brindar\u00e1 amplias oportunidades de observar la diversa fauna del parque, incluidas cuatro especies de monos y dos de perezosos. Tras un descanso en el puesto de los guardabosques para almorzar, continuaremos con una caminata m\u00e1s corta y accidentada de 1,5 horas que nos llevar\u00e1 a una hermosa cascada donde podr\u00e1s refrescarte y disfrutar de la serenidad del entorno. <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63647\" src=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/13-1.jpg\" alt=\"Parque Nacional Corcovado\" width=\"1300\" height=\"1000\" srcset=\"https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/13-1.jpg 1300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/13-1-300x231.jpg 300w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/13-1-1024x788.jpg 1024w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/13-1-768x591.jpg 768w, https:\/\/epicadventurescr.com\/wp-content\/uploads\/2024\/10\/13-1-600x462.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<p><span class=\"\">El d\u00eda concluye con un paseo en barco de vuelta a Sierpe y luego a Manuel Antonio tras la puesta de sol. Debido a las pol\u00edticas gubernamentales que limitan el n\u00famero de visitantes diarios al Parque Nacional de Corcovado, te recomendamos que hagas la reserva lo antes posible para asegurar tu plaza. <\/span><\/p>\n<\/div>\n<\/div>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\"><strong>\u00bfPor qu\u00e9 elegir Epic Adventures Costa Rica?<\/strong><\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">En Epic Adventures Costa Rica, nos enorgullecemos de ofrecer una experiencia meticulosamente elaborada que combina aventura, educaci\u00f3n y conservaci\u00f3n. Nuestras excursiones est\u00e1n dise\u00f1adas para proporcionar un conocimiento profundo de la biodiversidad \u00fanica de Corcovado, garantizando al mismo tiempo la m\u00e1xima seguridad y comodidad para nuestros hu\u00e9spedes. Nos comprometemos a promover pr\u00e1cticas tur\u00edsticas sostenibles que protejan y preserven los delicados ecosistemas del parque para las generaciones futuras.  <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\"><strong>\u00a1\u00danete a nosotros en la aventura de tu vida!<\/strong><\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">El Parque Nacional del Corcovado desde Manuel Antonio es una aventura que no te puedes perder.  <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><span class=\"\">\u00danete a nosotros en esta experiencia \u00fanica en la vida, y d\u00e9janos guiarte por las maravillas del destino biol\u00f3gicamente m\u00e1s intenso de Costa Rica. Para reservar tu excursi\u00f3n o para cualquier informaci\u00f3n adicional, env\u00edanos una nota con el siguiente formulario. \u00a1Estamos deseando crear contigo recuerdos inolvidables!  <\/span><\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\">Referencias:<\/p>\n<p>Sinac.go.cr. (2024). <i>Parque Nacional del Corcovado<\/i>. [online] Disponible en: https:\/\/www.sinac.go.cr\/en-us\/ac\/acosa\/pnc\/pages\/default.aspx [Consultado el 24 de octubre de 2024]. Fern\u00e1ndez, I. (2024). <i>Parque Nacional del Corcovado: Un refugio para una fauna \u00fanica<\/i>. [online] The Tico Times | Noticias de Costa Rica | Viajes | Bienes inmuebles. Disponible en: <a href=\"https:\/\/ticotimes.net\/2024\/10\/19\/corcovado-national-park-a-haven-for-unique-wildlife\" target=\"_blank\" rel=\"noopener\">https:\/\/ticotimes.net\/2024\/10\/19\/corcovado-national-park-a-haven-for-unique-wildlife<\/a> [Consultado el 24 de octubre de 2024].  <\/p>\n<p aria-live=\"polite\" aria-atomic=\"true\"><div class=\"frm_forms  with_frm_style frm_style_formidable-style\" id=\"frm_form_2_container\" data-token=\"b0c6bd3972ea1b091943762f3ecc2615\">\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_reserveyourtour\" data-token=\"b0c6bd3972ea1b091943762f3ecc2615\">\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Reserve your tour!<\/legend>\r\n<h3 class=\"frm_form_title\">Reserve your tour!<\/h3>\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"2\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_2\" id=\"frm_hide_fields_2\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"reserveyourtour\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_2\" name=\"frm_submit_entry_2\" value=\"02ef3c7534\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/posts\/63653\" \/><div id=\"frm_field_7_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <div  id=\"field_5p532_label\" class=\"frm_primary_label\">Name\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/div>\r\n    <fieldset aria-labelledby=\"field_5p532_label\">\n\t<legend class=\"frm_screen_reader frm_hidden\">\n\t\tName\t<\/legend>\n\n\t<div  class=\"frm_combo_inputs_container\" id=\"frm_combo_inputs_container_7\" data-name-layout=\"first_last\">\n\t\t\t\t\t<div\n\t\t\t\tid=\"frm_field_7-first_container\"\n\t\t\t\tclass=\"frm_form_field form-field frm_form_subfield-first  frm6\"\n\t\t\t\tdata-sub-field-name=\"first\"\n\t\t\t>\n\t\t\t\t<label for=\"field_5p532_first\" class=\"frm_screen_reader frm_hidden\">\n\t\t\t\t\tFirst\t\t\t\t<\/label>\n\n\t\t\t\t<input  type=\"text\" id=\"field_5p532_first\" value=\"\" name=\"item_meta[7][first]\" autocomplete=\"given-name\" data-reqmsg=\"Name cannot be blank.\" aria-required=\"true\" data-invmsg=\"Name no es v\u00e1lido\" aria-invalid=\"false\"  \/><div class=\"frm_description\" id=\"frm_field_7_first_desc\">First<\/div>\t\t\t<\/div>\n\t\t\t\t\t\t<div\n\t\t\t\tid=\"frm_field_7-last_container\"\n\t\t\t\tclass=\"frm_form_field form-field frm_form_subfield-last  frm6\"\n\t\t\t\tdata-sub-field-name=\"last\"\n\t\t\t>\n\t\t\t\t<label for=\"field_5p532_last\" class=\"frm_screen_reader frm_hidden\">\n\t\t\t\t\tLast\t\t\t\t<\/label>\n\n\t\t\t\t<input  type=\"text\" id=\"field_5p532_last\" value=\"\" name=\"item_meta[7][last]\" autocomplete=\"family-name\" data-reqmsg=\"Name cannot be blank.\" aria-required=\"true\" data-invmsg=\"Name no es v\u00e1lido\" aria-invalid=\"false\"  \/><div class=\"frm_description\" id=\"frm_field_7_last_desc\">Last<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/fieldset>\n\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_8_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container\">\r\n    <label for=\"field_xvhgf\" id=\"field_xvhgf_label\" class=\"frm_primary_label\">Email\r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_xvhgf\" name=\"item_meta[8]\" value=\"\"  data-reqmsg=\"Email cannot be blank.\" aria-required=\"true\" data-invmsg=\"Email is invalid\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_9_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_nrinz\" id=\"field_nrinz_label\" class=\"frm_primary_label\">Phone\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input type=\"tel\" id=\"field_nrinz\" name=\"item_meta[9]\" value=\"\"  data-invmsg=\"Phone is invalid\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_13_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_two_col\">\r\n    <div  id=\"field_eds5x_label\" class=\"frm_primary_label\">Pick the tours you'd like to do with us: \r\n        <span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n    <\/div>\r\n    <div class=\"frm_opt_container\" aria-labelledby=\"field_eds5x_label\" role=\"group\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-0\">\t\t\t<label  for=\"field_eds5x-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-0\" value=\"Manuel Antonio National Park Guided Walk\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   aria-required=\"true\"  \/> Manuel Antonio National Park Guided Walk<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-4\">\t\t\t<label  for=\"field_eds5x-4\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-4\" value=\"Rainmaker Guided Walk\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Rainmaker Guided Walk<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-5\">\t\t\t<label  for=\"field_eds5x-5\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-5\" value=\"Corcovado National Park from Manuel Antonio\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Corcovado National Park from Manuel Antonio<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-1\">\t\t\t<label  for=\"field_eds5x-1\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-1\" value=\"Damas Mangroves by boat\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Damas Mangroves by boat<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-2\">\t\t\t<label  for=\"field_eds5x-2\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-2\" value=\"Damas Mangroves by night\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Damas Mangroves by night<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-3\">\t\t\t<label  for=\"field_eds5x-3\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-3\" value=\"Damas Mangroves by Kayak\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Damas Mangroves by Kayak<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-6\">\t\t\t<label  for=\"field_eds5x-6\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-6\" value=\"Nauyaca Waterfalls\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Nauyaca Waterfalls<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-7\">\t\t\t<label  for=\"field_eds5x-7\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-7\" value=\"Night Walk\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Night Walk<\/label><\/div>\n\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_13-8\">\t\t\t<label  for=\"field_eds5x-8\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[13][]\" id=\"field_eds5x-8\" value=\"Sea Kayaking Tour\"  data-reqmsg=\"Pick the tours you&#039;d like to do with us:  cannot be blank.\" data-invmsg=\"Pick the tours you&#039;d like to do with us:  no es v\u00e1lido\"   \/> Sea Kayaking Tour<\/label><\/div>\n<\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_11_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_iak53\" id=\"field_iak53_label\" class=\"frm_primary_label\">Date\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_iak53\" name=\"item_meta[11]\" value=\"05\/13\/2026\"  maxlength=\"10\" data-frmval=\"05\/13\/2026\" data-invmsg=\"Date is invalid\" class=\"frm_date\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_14_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_4cv8c\" id=\"field_4cv8c_label\" class=\"frm_primary_label\">Number of Passengers\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input type=\"number\" id=\"field_4cv8c\" name=\"item_meta[14]\" value=\"\" data-invmsg=\"Number is invalid\" aria-invalid=\"false\"   min=\"0\" max=\"9999999\" step=\"any\" \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_15_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_md5uy\" id=\"field_md5uy_label\" class=\"frm_primary_label\">You are staying at: \r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <input  type=\"text\" id=\"field_md5uy\" name=\"item_meta[15]\" value=\"\"  data-invmsg=\"Text is invalid\" aria-invalid=\"false\"   \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_17_container\" class=\"frm_form_field form-field  frm_top_container frm12 frm_first\">\r\n    <label for=\"field_ctij8\" id=\"field_ctij8_label\" class=\"frm_primary_label\">Comments\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[17]\" id=\"field_ctij8\" rows=\"5\"  data-invmsg=\"Paragraph is invalid\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_19_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" id=\"field_nowbl_label\" class=\"frm_primary_label\">Captcha\r\n        <span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n    <\/label>\r\n    <div  id=\"field_nowbl\" class=\"frm-g-recaptcha\" data-sitekey=\"6LcsxcYhAAAAACGibGrn9XTbasGg3l4BovjDXubA\" data-size=\"invisible\" data-theme=\"light\"><\/div>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_21_container\" class=\"frm_form_field form-field \">\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit frm_final_submit\" type=\"submit\"   formnovalidate=\"formnovalidate\">Let&#039;s do it!<\/button>\r\n\r\n\r\n<\/div>\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_23_container\">\n\t\t\t<label for=\"field_ylnh6\" >\n\t\t\t\tSi eres humano, deja este campo en blanco.\t\t\t<\/label>\n\t\t\t<input  id=\"field_ylnh6\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[23]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"1O7hxS58bI43S83gIcs3Y55odFcPmGGDhnRfWlfnHsQ6FlVqkdwnayzE539T6XpB\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"148\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><\/form>\n<\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Parque Nacional del Corcovado es un testimonio de la belleza natural y la biodiversidad de Costa Rica. Este extraordinario lugar alberga una gran variedad de especies animales y vegetales \u00fanicas y poco comunes, muchas de las cuales est\u00e1n protegidas dentro de sus l\u00edmites. Descubre la Belleza Natural y la Biodiversidad del Parque Nacional de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":63640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[190,231],"tags":[],"class_list":["post-63653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es-2","category-sobre-nuestros-circuitos"],"_links":{"self":[{"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/posts\/63653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/comments?post=63653"}],"version-history":[{"count":1,"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/posts\/63653\/revisions"}],"predecessor-version":[{"id":66018,"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/posts\/63653\/revisions\/66018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/media\/63640"}],"wp:attachment":[{"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/media?parent=63653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/categories?post=63653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/epicadventurescr.com\/es\/wp-json\/wp\/v2\/tags?post=63653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}